{"id":12452,"date":"2025-11-20T20:22:38","date_gmt":"2025-11-20T19:22:38","guid":{"rendered":"https:\/\/blekleratoriginal.com\/product\/der-anarchist-kuenstlerexemplar-2"},"modified":"2025-11-20T23:03:09","modified_gmt":"2025-11-20T22:03:09","slug":"der-anarchist-kuenstlerexemplar-2","status":"publish","type":"product","link":"https:\/\/blekleratoriginal.com\/de\/produkt\/der-anarchist-kuenstlerexemplar-2","title":{"rendered":"Der Anarchist K\u00fcnstlerexemplar"},"content":{"rendered":"<p>K\u00fcnstlerexemplar einer signierten und auf 300 Exemplare limitierten Ausgabe, die 2021 ver\u00f6ffentlicht wurde. Der dreifarbige Siebdruck auf 300g Arches Papier misst 23 x 31cm (9 x 12 \u00bc in) und ist von einem vom K\u00fcnstler signierten Echtheitszertifikat begleitet. Die Abz\u00fcge sind auf XXX (30 Exemplare) nummeriert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>K\u00fcnstlerexemplar einer signierten und auf 300 Exemplare limitierten Ausgabe, die 2021 ver\u00f6ffentlicht wurde. Der dreifarbige Siebdruck auf 300g Arches Papier&#8230;<\/p>\n","protected":false},"featured_media":10058,"template":"","meta":[],"product_brand":[],"product_cat":[81],"product_tag":[],"class_list":{"0":"post-12452","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-print-de","7":"product_shipping_class-box-de","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/product\/12452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/media\/10058"}],"wp:attachment":[{"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/media?parent=12452"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/product_brand?post=12452"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/product_cat?post=12452"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/product_tag?post=12452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}