{"id":12448,"date":"2025-11-19T20:12:18","date_gmt":"2025-11-19T19:12:18","guid":{"rendered":"https:\/\/blekleratoriginal.com\/product\/the-king-kuenstlerischer-abzug"},"modified":"2025-11-19T20:54:45","modified_gmt":"2025-11-19T19:54:45","slug":"the-king-kuenstlerischer-abzug","status":"publish","type":"product","link":"https:\/\/blekleratoriginal.com\/de\/produkt\/the-king-kuenstlerischer-abzug","title":{"rendered":"The King K\u00fcnstlerexemplar"},"content":{"rendered":"<p>K\u00fcnstlerexemplar einer signierten und auf 300 Exemplare limitierten Ausgabe, die im Jahr 2023 ver\u00f6ffentlicht wurde. Die Abz\u00fcge sind auf XXX (30 Exemplare) nummeriert. <\/p>\n<p>Der dreifarbige Siebdruck auf Arches 300g misst 23 x 31 cm ( (9 x 12 \u00bc in), ist signiert und mit einem vom K\u00fcnstler signierten Echtheitszertifikat versehen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>K\u00fcnstlerexemplar einer signierten und auf 300 Exemplare limitierten Ausgabe, die im Jahr 2023 ver\u00f6ffentlicht wurde. Die Abz\u00fcge sind auf XXX&#8230;<\/p>\n","protected":false},"featured_media":12444,"template":"","meta":[],"product_brand":[],"product_cat":[81],"product_tag":[],"class_list":{"0":"post-12448","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-print-de","7":"product_shipping_class-box-de","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/product\/12448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/media\/12444"}],"wp:attachment":[{"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/media?parent=12448"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/product_brand?post=12448"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/product_cat?post=12448"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/product_tag?post=12448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}