{"id":12115,"date":"2024-12-02T16:53:02","date_gmt":"2024-12-02T15:53:02","guid":{"rendered":"https:\/\/blekleratoriginal.com\/product\/der-zentaur-schuetze-gelbe-edition-kuenstlerexemplar-ii-iii-2-3"},"modified":"2024-12-16T19:13:43","modified_gmt":"2024-12-16T18:13:43","slug":"der-zentaur-schuetze-gelbe-edition-kuenstlerexemplar-ii-iii-2-3","status":"publish","type":"product","link":"https:\/\/blekleratoriginal.com\/de\/produkt\/der-zentaur-schuetze-gelbe-edition-kuenstlerexemplar-ii-iii-2-3","title":{"rendered":"Der Zentaur (Sch\u00fctze), gelbe Edition; K\u00fcnstlerexemplar #II\/III (2\/3)"},"content":{"rendered":"<p>K\u00fcnstlerexemplar aus einer 2019 erschienenen Auflage von 12 Exemplaren, zweifarbige Serigraphie auf Arches 300g, 31X23cm; signiert, nummeriert und mit einem vom K\u00fcnstler signierten Echtheitszertifikat versehen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>K\u00fcnstlerexemplar aus einer 2019 erschienenen Auflage von 12 Exemplaren, zweifarbige Serigraphie auf Arches 300g, 31X23cm; signiert, nummeriert und mit einem&#8230;<\/p>\n","protected":false},"featured_media":12113,"template":"","meta":[],"product_brand":[],"product_cat":[81],"product_tag":[],"class_list":{"0":"post-12115","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-print-de","7":"product_shipping_class-box-de","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/product\/12115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/media\/12113"}],"wp:attachment":[{"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/media?parent=12115"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/product_brand?post=12115"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/product_cat?post=12115"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/blekleratoriginal.com\/de\/wp-json\/wp\/v2\/product_tag?post=12115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}